{"id":3899,"date":"2025-09-23T08:46:14","date_gmt":"2025-09-23T08:46:14","guid":{"rendered":"https:\/\/samilia.org\/?post_type=aiovg_videos&#038;p=3899"},"modified":"2025-09-23T08:46:14","modified_gmt":"2025-09-23T08:46:14","slug":"bars-a-ongles-lesclavage-moderne-derriere-les-vitrines-on-nest-pas-des-pigeons","status":"publish","type":"aiovg_videos","link":"https:\/\/samilia.org\/en\/video\/bars-a-ongles-lesclavage-moderne-derriere-les-vitrines-on-nest-pas-des-pigeons\/","title":{"rendered":"Bars \u00e0 ongles : l&#8217;esclavage moderne derri\u00e8re les vitrines &#8211; On n&#8217;est pas des Pigeons"},"content":{"rendered":"<p>Les produits et les conditions de travail dans des ongleries asiatiques sont r\u00e9put\u00e9s douteux. Et ce ne serait rien, compar\u00e9 \u00e0 des pratiques encore plus choquantes : trafic d\u2019\u00eatres humains et exploitation \u00e9conomique.<\/p>\n<p>A Bruxelles, les ongleries asiatiques qui s\u2019installent sont de plus en plus nombreuses. Une des raisons de leur succ\u00e8s : des tout petits prix. Ce qui pose question, ce sont les travailleurs, au noir ou en situation ill\u00e9gale, qui travaillent dans ces ongleries.<\/p>\n<p>\u201cC\u2019est le nouvel esclavage moderne.\u201d r\u00e9sume pour nous Sophie Jekeler, pr\u00e9sidente de la fondation Samilia, qui lutte contre toutes les formes de traites d\u2019\u00eatres humains. Derri\u00e8re le vernis de ces bars \u00e0 ongles, la r\u00e9alit\u00e9 ne serait en effet pas toujours belle \u00e0 voir. En plein c\u0153ur de la capitale europ\u00e9enne, Bruxelles, des ongleries asiatiques se sont install\u00e9es c\u00f4te \u00e0 c\u00f4te par dizaines. Elles investissent maintenant aussi d\u2019autres villes du royaume, comme Namur ou Li\u00e8ge. La raison de leur succ\u00e8s : des prix cass\u00e9s.<\/p>\n<p>L\u2019emploi de travailleurs non d\u00e9clar\u00e9s et en situation ill\u00e9gale expliquerait ces tarifs bon march\u00e9, comme nous l\u2019explique Bruno Devill\u00e9, inspecteur \u00e0 l\u2019ONSS, l\u2019Office national de s\u00e9curit\u00e9 sociale, attach\u00e9 \u00e0 ce dossier \u201cdes ongleries asiatiques\u201d depuis sept ans : \u201cCe dont on est certains, maintenant, c\u2019est que ces personnes-l\u00e0 sont des migrants mais d\u00e9j\u00e0 qui migrent dans le cadre d\u2019un trafic organis\u00e9 par des bandes criminelles. Il faut savoir que dans les 39 morts d\u2019Essex, 39 migrants retrouv\u00e9s morts dans un camion, quelqu\u2019un \u00e9tait pass\u00e9 par ces ongleries, \u00e7a, on en a la preuve.\u201d Une fondation de lutte contre la traite des \u00eatres humains, la fondation Samilia, parle d\u2019esclavage moderne. Elle a m\u00eame fait de cette question une campagne pour sensibiliser les consommateurs belges, intitul\u00e9e \u201cSous le vernis, l\u2019exploitation humaine.\u201d Sophie Jekeler, pr\u00e9sidente de la fondation Samilia, nous parle du ph\u00e9nom\u00e8ne des ongleries asiatiques qu\u2019elle conna\u00eet bien : \u201cLa premi\u00e8re chose, on confisque les passeports. Deuxi\u00e8me chose, on les menace et on menace leurs familles rest\u00e9es au pays de s\u00e9vices assez graves. Ils ne parlent pas la langue. Ils n\u2019ont pas d\u2019autres points de chute. Ils sont log\u00e9s o\u00f9 ils sont exploit\u00e9s.\u201d L\u2019argent qu\u2019ils rapporteraient partirait en grande partie vers leur pays d\u2019origine. \u201cLes gens qui migrent vers l\u2019Europe cr\u00e9ent des dettes au Vietnam, donc, on est entre, pour donner une fourchette, 20.000 et 50.000 euros de dettes et ils doivent les rembourser.\u201d nous explique Bruno Devill\u00e9, inspecteur \u00e0 l\u2019ONSS.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les produits et les conditions de travail dans des ongleries asiatiques sont r\u00e9put\u00e9s douteux. Et ce ne serait rien, compar\u00e9 \u00e0 des pratiques encore plus choquantes : trafic d\u2019\u00eatres humains [&hellip;]<\/p>\n","protected":false},"author":2,"comment_status":"closed","ping_status":"closed","template":"","aiovg_categories":[105],"aiovg_tags":[100,137],"class_list":["post-3899","aiovg_videos","type-aiovg_videos","status-publish","has-post-thumbnail","hentry","aiovg_categories-divers","aiovg_tags-exploitation-economique","aiovg_tags-onglerie"],"acf":[],"_links":{"self":[{"href":"https:\/\/samilia.org\/en\/wp-json\/wp\/v2\/aiovg_videos\/3899","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/samilia.org\/en\/wp-json\/wp\/v2\/aiovg_videos"}],"about":[{"href":"https:\/\/samilia.org\/en\/wp-json\/wp\/v2\/types\/aiovg_videos"}],"author":[{"embeddable":true,"href":"https:\/\/samilia.org\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/samilia.org\/en\/wp-json\/wp\/v2\/comments?post=3899"}],"wp:attachment":[{"href":"https:\/\/samilia.org\/en\/wp-json\/wp\/v2\/media?parent=3899"}],"wp:term":[{"taxonomy":"aiovg_categories","embeddable":true,"href":"https:\/\/samilia.org\/en\/wp-json\/wp\/v2\/aiovg_categories?post=3899"},{"taxonomy":"aiovg_tags","embeddable":true,"href":"https:\/\/samilia.org\/en\/wp-json\/wp\/v2\/aiovg_tags?post=3899"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}